{"id":20305,"date":"2024-08-07T07:58:36","date_gmt":"2024-08-07T07:58:36","guid":{"rendered":"https:\/\/www.eurofirmsfoundation.org\/es\/?p=20305"},"modified":"2024-08-07T07:58:38","modified_gmt":"2024-08-07T07:58:38","slug":"eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo","status":"publish","type":"post","link":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/","title":{"rendered":"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo"},"content":{"rendered":"\n<p><strong>Eurofirms Foundation, entidad que trabaja para la inclusi\u00f3n laboral de personas con discapacidad, firma un acuerdo de colaboraci\u00f3n con Autismo Espa\u00f1a con el objetivo de mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.<\/strong> Esta alianza permitir\u00e1 a las personas con autismo inscribirse en las ofertas laborales impulsadas por Eurofirms Foundation y participar en sus programas formativos, abriendo nuevas oportunidades para su desarrollo profesional y personal.<\/p>\n\n\n\n<p>En la actualidad, m\u00e1s del 75% de las personas adultas con autismo est\u00e1n desempleadas y no realizan ninguna actividad productiva o laboral, convirti\u00e9ndolos en el colectivo de la discapacidad con la tasa m\u00e1s alta de desempleo. <strong>Esta situaci\u00f3n subraya la importancia de iniciativas como la presente colaboraci\u00f3n, que busca revertir esta estad\u00edstica mediante la promoci\u00f3n de la empleabilidad y formaci\u00f3n.<\/strong><\/p>\n\n\n\n<p><strong>En este marco, Eurofirms Foundation y Autismo Espa\u00f1a est\u00e1n comprometidos en proporcionar herramientas y recursos que faciliten la inclusi\u00f3n laboral de personas con autismo<\/strong>, ofreciendo no solo acceso a oportunidades de empleo, sino tambi\u00e9n programas de formaci\u00f3n dise\u00f1ados para mejorar sus habilidades. Esta colaboraci\u00f3n tiene como objetivo crear un entorno m\u00e1s inclusivo y accesible, donde las personas con autismo puedan desarrollar su potencial dentro del mundo laboral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eurofirms Foundation, entidad que trabaja para la inclusi\u00f3n laboral de personas con discapacidad, firma un acuerdo de colaboraci\u00f3n con Autismo Espa\u00f1a con el objetivo de mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno. Esta alianza permitir\u00e1 a las personas con autismo inscribirse en las ofertas laborales impulsadas por Eurofirms Foundation y participar en sus programas formativos, abriendo nuevas oportunidades para su desarrollo profesional y personal. En la actualidad, m\u00e1s del 75% de las personas adultas con autismo est\u00e1n desempleadas y no realizan ninguna actividad productiva o laboral, convirti\u00e9ndolos en el colectivo de la discapacidad con la tasa m\u00e1s alta de desempleo. Esta situaci\u00f3n subraya la importancia de iniciativas como la presente colaboraci\u00f3n, que busca revertir esta estad\u00edstica mediante la promoci\u00f3n de la empleabilidad y formaci\u00f3n. En este marco, Eurofirms Foundation y Autismo Espa\u00f1a est\u00e1n comprometidos en proporcionar herramientas y recursos que faciliten la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":20306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[32],"class_list":["post-20305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-alianzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Eurofirms Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T07:58:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T07:58:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eurofirmsfoundation.org\/es\/wp-content\/uploads\/sites\/2\/2024\/08\/shutterstock_2014536923-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fundacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fundacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/\",\"url\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/\",\"name\":\"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#website\"},\"datePublished\":\"2024-08-07T07:58:36+00:00\",\"dateModified\":\"2024-08-07T07:58:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/2c81dca7a893106910ec9d90923668c8\"},\"description\":\"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#website\",\"url\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/\",\"name\":\"Fundaci\u00f3n Eurofirms Espa\u00f1a\",\"description\":\"Otro sitio m\u00e1s de Fundaci\u00f3n Eurofirms \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/2c81dca7a893106910ec9d90923668c8\",\"name\":\"fundacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/494c0763720587c01d08b9d2a7c93101a227f76c9396143c8d56d945460b379e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/494c0763720587c01d08b9d2a7c93101a227f76c9396143c8d56d945460b379e?s=96&d=mm&r=g\",\"caption\":\"fundacio\"},\"url\":\"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/author\/fundacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a","description":"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/","og_locale":"es_ES","og_type":"article","og_title":"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a","og_description":"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.","og_url":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/","og_site_name":"Fundaci\u00f3n Eurofirms Espa\u00f1a","article_published_time":"2024-08-07T07:58:36+00:00","article_modified_time":"2024-08-07T07:58:38+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.eurofirmsfoundation.org\/es\/wp-content\/uploads\/sites\/2\/2024\/08\/shutterstock_2014536923-1.jpg","type":"image\/jpeg"}],"author":"fundacio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fundacio","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/","url":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/","name":"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo - Fundaci\u00f3n Eurofirms Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#website"},"datePublished":"2024-08-07T07:58:36+00:00","dateModified":"2024-08-07T07:58:38+00:00","author":{"@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/2c81dca7a893106910ec9d90923668c8"},"description":"El objetivo es mejorar la formaci\u00f3n, participaci\u00f3n y la empleabilidad de personas con autismo y de su entorno.","breadcrumb":{"@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/eurofirms-foundation-y-autismo-espana-firman-un-acuerdo-para-impulsar-la-empleabilidad-de-las-personas-con-autismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/"},{"@type":"ListItem","position":2,"name":"Eurofirms Foundation y Autismo Espa\u00f1a firman un acuerdo para impulsar la empleabilidad de las personas con autismo"}]},{"@type":"WebSite","@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#website","url":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/","name":"Fundaci\u00f3n Eurofirms Espa\u00f1a","description":"Otro sitio m\u00e1s de Fundaci\u00f3n Eurofirms ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/2c81dca7a893106910ec9d90923668c8","name":"fundacio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/494c0763720587c01d08b9d2a7c93101a227f76c9396143c8d56d945460b379e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/494c0763720587c01d08b9d2a7c93101a227f76c9396143c8d56d945460b379e?s=96&d=mm&r=g","caption":"fundacio"},"url":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/noticias\/author\/fundacio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/posts\/20305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/comments?post=20305"}],"version-history":[{"count":1,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/posts\/20305\/revisions"}],"predecessor-version":[{"id":20308,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/posts\/20305\/revisions\/20308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/media\/20306"}],"wp:attachment":[{"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/media?parent=20305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/categories?post=20305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eurofirmsfoundation.org\/es\/es\/wp-json\/wp\/v2\/tags?post=20305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}